{"id":28,"count":1,"description":"","link":"https:\/\/luciusalmeida.com\/blog\/tag\/electronic-vehicles\/","name":"electronic vehicles","slug":"electronic-vehicles","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/luciusalmeida.com\/blog\/wp-json\/wp\/v2\/tags\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luciusalmeida.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/luciusalmeida.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/luciusalmeida.com\/blog\/wp-json\/wp\/v2\/posts?tags=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}